{"id":7677,"date":"2021-08-22T13:02:35","date_gmt":"2021-08-22T18:02:35","guid":{"rendered":"https:\/\/laverdeoveja.com\/lasana-vegetariana-con-ricota\/"},"modified":"2022-02-05T18:25:13","modified_gmt":"2022-02-05T23:25:13","slug":"lasana-vegetariana-con-ricota","status":"publish","type":"post","link":"https:\/\/laverdeoveja.com\/es\/lasana-vegetariana-con-ricota\/","title":{"rendered":"Lasa\u00f1a vegetariana con ricota"},"content":{"rendered":"<!--themify_builder_content-->\n<div id=\"themify_builder_content-7677\" data-postid=\"7677\" class=\"themify_builder_content themify_builder_content-7677 themify_builder tf_clear\">\n                    <div  data-lazy=\"1\" class=\"module_row themify_builder_row tb_2pn3572 tb_first tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_a3om573 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_6um0574   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <p>Lasa\u00f1a vegetariana con ricota<\/p>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                        <\/div>\n        <\/div>\n                        <div  data-lazy=\"1\" class=\"module_row themify_builder_row tb_6m8z572 tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_ds69575 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_1tcf575   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <p>Receta proporcionada por: Sonja Overhiser en <a href=\"https:\/\/www.acouplecooks.com\/vegetarian-lasagna-with-ricotta\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.acouplecooks.com\/vegetarian-lasagna-with-ricotta\/<\/a><\/p>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module text -->\n<div  class=\"module module-text tb_k6v3576   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <p><strong>Porciones<\/strong> : 9 | <strong>Tiempo de preparaci\u00f3n:<\/strong> 45 minutos | <strong>Tiempo de cocci\u00f3n<\/strong> : 50 minutos<\/p>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module text -->\n<div  class=\"module module-text tb_7zuo65   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <p><strong>\u00a1Esta receta de lasa\u00f1a vegetariana es un placer total! El relleno f\u00e1cil de espinacas y queso ricotta es cl\u00e1sico y cremoso.<\/strong>.<\/p>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                        <\/div>\n        <\/div>\n                        <div  data-lazy=\"1\" class=\"module_row themify_builder_row tb_f7dc572 tf_w\">\n                        <div class=\"row_inner gutter-narrow col_align_top tb_col_count_2 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col4-2 tb_sfu5576 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_hxrf576   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <h3><strong>INGREDIENTES<\/strong><\/h3>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module text -->\n<div  class=\"module module-text tb_dd1b321   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <p><strong>Para la salsa de tomate (o sustituya 4 tazas de su salsa marinara favorita)<\/strong><\/p>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module text -->\n<div  class=\"module module-text tb_me5s577   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <ul>\n<li><span data-amount=\"4\">4<\/span> dientes de ajo grandes<\/li>\n<li><span data-amount=\"2\" data-unit=\"tablespoon\">2 cucharadas de<\/span> mantequilla sin sal<\/li>\n<li><span data-amount=\"1\">1<\/span> lata de 28 onzas de tomates triturados, asados al fuego si es posible<\/li>\n<li><span data-amount=\"1\">1<\/span> lata de salsa de tomate de 15 onzas, asada al fuego si es posible<\/li>\n<li><span data-amount=\"1\" data-unit=\"teaspoon\">1 cucharadita<\/span> de albahaca seca<\/li>\n<li><span data-amount=\"1\" data-unit=\"teaspoon\">1 cucharadita<\/span> de estrag\u00f3n seco (u or\u00e9gano)<\/li>\n<li><span data-amount=\"0.75\" data-unit=\"teaspoon\">\u00be cucharadita<\/span> <a class=\"tasty-link\" href=\"https:\/\/www.acouplecooks.com\/what-is-kosher-salt\/\" target=\"_blank\" rel=\"noopener\" data-tasty-links-no-disclosure=\"\">de sal kosher<\/a><\/li>\n<li><span data-amount=\"1\" data-unit=\"tablespoon\">1 cucharada de<\/span> maicena (o almid\u00f3n de arrurruz)<\/li>\n<\/ul>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module text -->\n<div  class=\"module module-text tb_ugk529   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <p><strong>para la lasa\u00f1a<\/strong><\/p>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module text -->\n<div  class=\"module module-text tb_qx6q443   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <ul>\n<li><span data-amount=\"10\">10<\/span> a <span data-amount=\"12\">12<\/span> fideos de lasa\u00f1a ( <span data-amount=\"8\" data-unit=\"ounce\">8 onzas<\/span> , sin gluten seg\u00fan sea necesario)*<\/li>\n<li><span data-amount=\"5\" data-unit=\"ounce\">5 onzas de<\/span> espinacas tiernas** (u <span data-amount=\"8\" data-unit=\"cup\">8 tazas de<\/span> espinacas picadas)<\/li>\n<li><span data-amount=\"2\" data-unit=\"tablespoon\">2 cucharadas<\/span> de tomillo fresco picado<\/li>\n<li>Zest of <span data-amount=\"0.5\">1\/2<\/span> lemon (about <span data-amount=\"2\" data-unit=\"teaspoon\">2 teaspoons<\/span>)<\/li>\n<li><span data-amount=\"0.25\" data-unit=\"teaspoon\">\u00bc de cucharadita<\/span> de nuez moscada molida<\/li>\n<li><span data-amount=\"16\" data-unit=\"ounce\">16 onzas<\/span> ( <span data-amount=\"2\" data-unit=\"cup\">2 tazas<\/span> ) de queso ricotta<\/li>\n<li><span data-amount=\"1\" data-unit=\"cup\">1 taza de<\/span> queso parmesano rallado, dividido<\/li>\n<li><span data-amount=\"3\" data-unit=\"cup\">3 tazas<\/span> ( <span data-amount=\"12\" data-unit=\"ounce\">12 onzas<\/span> ) de queso mozzarella rallado, cantidad dividida<\/li>\n<li><span data-amount=\"1\" data-unit=\"teaspoon\">1 cucharadita<\/span> de <a class=\"tasty-link\" href=\"https:\/\/www.acouplecooks.com\/what-is-kosher-salt\/\" target=\"_blank\" rel=\"noopener\" data-tasty-links-no-disclosure=\"\">sal kosher<\/a><\/li>\n<li>Pimienta negra molida fresca<\/li>\n<\/ul>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module text -->\n<div  class=\"module module-text tb_m8ui839   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <h3><strong>NOTAS<\/strong><\/h3>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module text -->\n<div  class=\"module module-text tb_ymrq397   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <div class=\"tasty-recipes-notes-body\" data-tasty-recipes-customization=\"body-color.color\">\n<p>*Si usa fideos de lasa\u00f1a frescos, no es necesario hervirlos. <\/p>\n<p>**Tambi\u00e9n puede sustituir \u00be taza de espinacas congeladas. Descong\u00e9lalo y exprime el exceso de l\u00edquido: puedes saltarte el paso de cocci\u00f3n. <\/p>\n<\/div>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                    <div  data-lazy=\"1\" class=\"module_column tb-column col4-2 tb_pja6577 last\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_yw1e577   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <h3><strong>DIRECCIONES<\/strong><\/h3>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module text -->\n<div  class=\"module module-text tb_gpys577   \" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <div data-tasty-recipes-customization=\"body-color.color\">\n<ol>\n<li id=\"instruction-step-1\"><strong>Precalentar:<\/strong> Precaliente el horno a 375 grados Fahrenheit.<\/li>\n<li id=\"instruction-step-2\"><strong>Hervir los fideos*:<\/strong> Poner a hervir una olla grande con agua bien salada. Hervir los fideos hasta que est\u00e9n justo antes de que est\u00e9n al dente, de acuerdo con las instrucciones del paquete, revolviendo con frecuencia. Escurra los fideos, luego roc\u00ede una bandeja para hornear con un poco de aceite de oliva. Coloque los fideos planos sobre la hoja, luego volt\u00e9elos para que se cubran con aceite de oliva para evitar que se peguen.<\/li>\n<li id=\"instruction-step-3\"><strong>Preparar la salsa de tomate (o saltear con marinara comprada):<\/strong> <a class=\"tasty-link\" href=\"https:\/\/www.acouplecooks.com\/how-to-mince-garlic\/\" target=\"_blank\" rel=\"noopener\" data-tasty-links-no-disclosure=\"\">Picar el ajo<\/a> . Derrita la mantequilla en una cacerola a fuego medio. Agregue el ajo y saltee, revolviendo con frecuencia. Una vez que el ajo est\u00e9 fragante despu\u00e9s de aproximadamente 1 o 2 minutos, baje el fuego y agregue con cuidado los tomates, la salsa de tomate, la albahaca, el estrag\u00f3n u or\u00e9gano, <a class=\"tasty-link\" href=\"https:\/\/www.acouplecooks.com\/what-is-kosher-salt\/\" target=\"_blank\" rel=\"noopener\" data-tasty-links-no-disclosure=\"\">la sal kosher<\/a> y varios granos de pimienta negra molida. Retire \u00bc de taza de la salsa y revu\u00e9lvala con la maicena, luego agr\u00e9guela nuevamente a la sart\u00e9n (esto ayuda a espesar la salsa). Cocine a fuego lento mientras hace el resto de la receta, al menos 15 minutos. Cuando est\u00e9 listo para usar, retire la sart\u00e9n del fuego.<\/li>\n<li id=\"instruction-step-4\"><strong>Marchitar las espinacas:<\/strong> En una sart\u00e9n grande, amontone las verduras y \u00bc de taza de agua en la sart\u00e9n y cocine, revolviendo con frecuencia, hasta que est\u00e9n completamente marchitas y reducidas, aproximadamente 3 minutos (las verduras se reducen significativamente al cocinar; si es necesario, saltee en lotes). Espolvorear con 2 pizcas de <a class=\"tasty-link\" href=\"https:\/\/www.acouplecooks.com\/what-is-kosher-salt\/\" target=\"_blank\" rel=\"noopener\" data-tasty-links-no-disclosure=\"\">sal kosher<\/a> y revuelva, luego retire del fuego y deje que se enfr\u00ede un poco. Una vez enfriado, use sus manos para exprimir todo el exceso de l\u00edquido y des\u00e9chelo. Picar las espinacas en trozos grandes.<\/li>\n<li id=\"instruction-step-5\"><strong>Preparar el relleno de queso:<\/strong> Despalillar el tomillo y picar las hojas. Agregue 1 \u00bd cucharadas de tomillo a un taz\u00f3n mediano y reserve aproximadamente \u00bd cucharada para cubrir la lasa\u00f1a. En el taz\u00f3n, agregue la ralladura de lim\u00f3n, la nuez moscada, el queso ricotta, \u00be de taza de queso parmesano, 2 tazas de queso mozzarella rallado, <a class=\"tasty-link\" href=\"https:\/\/www.acouplecooks.com\/what-is-kosher-salt\/\" target=\"_blank\" rel=\"noopener\" data-tasty-links-no-disclosure=\"\">sal kosher<\/a> y varios granos de pimienta negra. Revuelve para combinar.<\/li>\n<li id=\"instruction-step-6\"><strong>Coloque la lasa\u00f1a en capas:<\/strong> en una fuente para hornear de 9 \u00abx 13\u00bb, extienda \u00bd taza de salsa de tomate en el fondo de la fuente. Luego cubra con 1 capa de fideos, la mitad de la mezcla de queso (en porciones y luego exti\u00e9ndala), la mitad de las verduras y aproximadamente 1 taza de salsa de tomate. Repita nuevamente: 1 capa de fideos (es posible que deba cortar un fideo por la mitad para el costado, dependiendo de su sart\u00e9n), la mezcla de queso restante, las verduras restantes y 1 taza de salsa de tomate. Finalmente, cubra con fideos (nuevamente, es posible que deba cortar un fideo por la mitad para la capa superior), luego las 1 \u00bd tazas restantes de la salsa de tomate. Espolvorea toda la parte superior con la 1 taza restante de queso mozzarella, \u00bc de taza de queso parmesano y \u00bd cucharada de tomillo.<\/li>\n<li id=\"instruction-step-7\"><strong>Hornea la lasa\u00f1a:<\/strong> Cubra la fuente con papel aluminio y hornee por 40 minutos. Retire con cuidado el papel aluminio y hornee otros 10 minutos, hasta que burbujee y se dore. Deje reposar durante 15 minutos antes de servir (esto permite que la lasa\u00f1a se asiente). Las sobras se pueden refrigerar durante 2 a 3 d\u00edas y recalentar en un horno a 375 \u00b0F.<\/li>\n<\/ol>\n<\/div>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                        <\/div>\n        <\/div>\n                        <div  data-lazy=\"1\" class=\"module_row themify_builder_row tb_l14p572 tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_lh1p577 first\">\n                    <!-- module buttons -->\n<div  class=\"module module-buttons tb_po49577 buttons-horizontal solid  rounded\" data-lazy=\"1\">\n        <div class=\"module-buttons-item tf_in_flx\">\n                        <a href=\"https:\/\/laverdeoveja.com\/shop\/ricotta\/\" class=\"ui builder_button tf_in_flx transparent\" target=\"_blank\" rel=\"noopener\">\n                                    <em><svg  class=\"tf_fa tf-ti-shopping-cart\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" aria-hidden=\"true\"><use href=\"#tf-ti-shopping-cart\" xlink:href=\"#tf-ti-shopping-cart\"><\/use><\/svg><\/em>                                        Comprar ricota                                        <\/a>\n                <\/div>\n            <\/div>\n<!-- \/module buttons -->\n        <\/div>\n                        <\/div>\n        <\/div>\n        <\/div>\n<!--\/themify_builder_content-->","protected":false},"excerpt":{"rendered":"<p>Deliciosas hamburguesas de cordero rellenas de tu queso de oveja favorito. \u00a1mmm!<\/p>\n","protected":false},"author":2,"featured_media":7540,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[254,255],"tags":[],"class_list":["post-7677","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recetas","category-recetas-de-queso","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Deliciosas hamburguesas de cordero rellenas de tu queso de oveja favorito. \u00a1mmm!\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Heather Steyn\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/laverdeoveja.com\/es\/lasana-vegetariana-con-ricota\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Verde Oveja -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Lasa\u00f1a vegetariana con ricota - Verde Oveja\" \/>\n\t\t<meta property=\"og:description\" content=\"Deliciosas hamburguesas de cordero rellenas de tu queso de oveja favorito. \u00a1mmm!\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/laverdeoveja.com\/es\/lasana-vegetariana-con-ricota\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-08-22T18:02:35+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-02-05T23:25:13+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Lasa\u00f1a vegetariana con ricota - Verde Oveja\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Deliciosas hamburguesas de cordero rellenas de tu queso de oveja favorito. \u00a1mmm!\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/lasana-vegetariana-con-ricota\\\/#blogposting\",\"name\":\"Lasa\\u00f1a vegetariana con ricota - Verde Oveja\",\"headline\":\"Lasa\\u00f1a vegetariana con ricota\",\"author\":{\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/author\\\/laverdeoveja\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/laverdeoveja.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Vegetarian-Lasagna-011.jpg\",\"width\":800,\"height\":1067},\"datePublished\":\"2021-08-22T13:02:35-05:00\",\"dateModified\":\"2022-02-05T18:25:13-05:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/lasana-vegetariana-con-ricota\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/lasana-vegetariana-con-ricota\\\/#webpage\"},\"articleSection\":\"Recetas, recetas de queso\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/lasana-vegetariana-con-ricota\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/category\\\/recetas\\\/#listItem\",\"name\":\"Recetas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/category\\\/recetas\\\/#listItem\",\"position\":2,\"name\":\"Recetas\",\"item\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/category\\\/recetas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/category\\\/recetas\\\/recetas-de-queso\\\/#listItem\",\"name\":\"recetas de queso\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/category\\\/recetas\\\/recetas-de-queso\\\/#listItem\",\"position\":3,\"name\":\"recetas de queso\",\"item\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/category\\\/recetas\\\/recetas-de-queso\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/lasana-vegetariana-con-ricota\\\/#listItem\",\"name\":\"Lasa\\u00f1a vegetariana con ricota\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/category\\\/recetas\\\/#listItem\",\"name\":\"Recetas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/lasana-vegetariana-con-ricota\\\/#listItem\",\"position\":4,\"name\":\"Lasa\\u00f1a vegetariana con ricota\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/category\\\/recetas\\\/recetas-de-queso\\\/#listItem\",\"name\":\"recetas de queso\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/#organization\",\"name\":\"Verde Oveja\",\"url\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/author\\\/laverdeoveja\\\/#author\",\"url\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/author\\\/laverdeoveja\\\/\",\"name\":\"Heather Steyn\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/lasana-vegetariana-con-ricota\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4801d072781bd5a672144bf8efa96f1d13d91712f78bfa6ee68d27157723d3bd?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Heather Steyn\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/lasana-vegetariana-con-ricota\\\/#webpage\",\"url\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/lasana-vegetariana-con-ricota\\\/\",\"name\":\"Lasa\\u00f1a vegetariana con ricota - Verde Oveja\",\"description\":\"Deliciosas hamburguesas de cordero rellenas de tu queso de oveja favorito. \\u00a1mmm!\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/lasana-vegetariana-con-ricota\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/author\\\/laverdeoveja\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/author\\\/laverdeoveja\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/laverdeoveja.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Vegetarian-Lasagna-011.jpg\",\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/lasana-vegetariana-con-ricota\\\/#mainImage\",\"width\":800,\"height\":1067},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/lasana-vegetariana-con-ricota\\\/#mainImage\"},\"datePublished\":\"2021-08-22T13:02:35-05:00\",\"dateModified\":\"2022-02-05T18:25:13-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/\",\"name\":\"Verde Oveja\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Lasa\u00f1a vegetariana con ricota - Verde Oveja","description":"Deliciosas hamburguesas de cordero rellenas de tu queso de oveja favorito. \u00a1mmm!","canonical_url":"https:\/\/laverdeoveja.com\/es\/lasana-vegetariana-con-ricota\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/laverdeoveja.com\/es\/lasana-vegetariana-con-ricota\/#blogposting","name":"Lasa\u00f1a vegetariana con ricota - Verde Oveja","headline":"Lasa\u00f1a vegetariana con ricota","author":{"@id":"https:\/\/laverdeoveja.com\/es\/author\/laverdeoveja\/#author"},"publisher":{"@id":"https:\/\/laverdeoveja.com\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/laverdeoveja.com\/wp-content\/uploads\/2021\/08\/Vegetarian-Lasagna-011.jpg","width":800,"height":1067},"datePublished":"2021-08-22T13:02:35-05:00","dateModified":"2022-02-05T18:25:13-05:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/laverdeoveja.com\/es\/lasana-vegetariana-con-ricota\/#webpage"},"isPartOf":{"@id":"https:\/\/laverdeoveja.com\/es\/lasana-vegetariana-con-ricota\/#webpage"},"articleSection":"Recetas, recetas de queso"},{"@type":"BreadcrumbList","@id":"https:\/\/laverdeoveja.com\/es\/lasana-vegetariana-con-ricota\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/laverdeoveja.com\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/laverdeoveja.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/laverdeoveja.com\/es\/category\/recetas\/#listItem","name":"Recetas"}},{"@type":"ListItem","@id":"https:\/\/laverdeoveja.com\/es\/category\/recetas\/#listItem","position":2,"name":"Recetas","item":"https:\/\/laverdeoveja.com\/es\/category\/recetas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/laverdeoveja.com\/es\/category\/recetas\/recetas-de-queso\/#listItem","name":"recetas de queso"},"previousItem":{"@type":"ListItem","@id":"https:\/\/laverdeoveja.com\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/laverdeoveja.com\/es\/category\/recetas\/recetas-de-queso\/#listItem","position":3,"name":"recetas de queso","item":"https:\/\/laverdeoveja.com\/es\/category\/recetas\/recetas-de-queso\/","nextItem":{"@type":"ListItem","@id":"https:\/\/laverdeoveja.com\/es\/lasana-vegetariana-con-ricota\/#listItem","name":"Lasa\u00f1a vegetariana con ricota"},"previousItem":{"@type":"ListItem","@id":"https:\/\/laverdeoveja.com\/es\/category\/recetas\/#listItem","name":"Recetas"}},{"@type":"ListItem","@id":"https:\/\/laverdeoveja.com\/es\/lasana-vegetariana-con-ricota\/#listItem","position":4,"name":"Lasa\u00f1a vegetariana con ricota","previousItem":{"@type":"ListItem","@id":"https:\/\/laverdeoveja.com\/es\/category\/recetas\/recetas-de-queso\/#listItem","name":"recetas de queso"}}]},{"@type":"Organization","@id":"https:\/\/laverdeoveja.com\/es\/#organization","name":"Verde Oveja","url":"https:\/\/laverdeoveja.com\/es\/"},{"@type":"Person","@id":"https:\/\/laverdeoveja.com\/es\/author\/laverdeoveja\/#author","url":"https:\/\/laverdeoveja.com\/es\/author\/laverdeoveja\/","name":"Heather Steyn","image":{"@type":"ImageObject","@id":"https:\/\/laverdeoveja.com\/es\/lasana-vegetariana-con-ricota\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4801d072781bd5a672144bf8efa96f1d13d91712f78bfa6ee68d27157723d3bd?s=96&d=mm&r=g","width":96,"height":96,"caption":"Heather Steyn"}},{"@type":"WebPage","@id":"https:\/\/laverdeoveja.com\/es\/lasana-vegetariana-con-ricota\/#webpage","url":"https:\/\/laverdeoveja.com\/es\/lasana-vegetariana-con-ricota\/","name":"Lasa\u00f1a vegetariana con ricota - Verde Oveja","description":"Deliciosas hamburguesas de cordero rellenas de tu queso de oveja favorito. \u00a1mmm!","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/laverdeoveja.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/laverdeoveja.com\/es\/lasana-vegetariana-con-ricota\/#breadcrumblist"},"author":{"@id":"https:\/\/laverdeoveja.com\/es\/author\/laverdeoveja\/#author"},"creator":{"@id":"https:\/\/laverdeoveja.com\/es\/author\/laverdeoveja\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/laverdeoveja.com\/wp-content\/uploads\/2021\/08\/Vegetarian-Lasagna-011.jpg","@id":"https:\/\/laverdeoveja.com\/es\/lasana-vegetariana-con-ricota\/#mainImage","width":800,"height":1067},"primaryImageOfPage":{"@id":"https:\/\/laverdeoveja.com\/es\/lasana-vegetariana-con-ricota\/#mainImage"},"datePublished":"2021-08-22T13:02:35-05:00","dateModified":"2022-02-05T18:25:13-05:00"},{"@type":"WebSite","@id":"https:\/\/laverdeoveja.com\/es\/#website","url":"https:\/\/laverdeoveja.com\/es\/","name":"Verde Oveja","inLanguage":"es-ES","publisher":{"@id":"https:\/\/laverdeoveja.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Verde Oveja -","og:type":"article","og:title":"Lasa\u00f1a vegetariana con ricota - Verde Oveja","og:description":"Deliciosas hamburguesas de cordero rellenas de tu queso de oveja favorito. \u00a1mmm!","og:url":"https:\/\/laverdeoveja.com\/es\/lasana-vegetariana-con-ricota\/","article:published_time":"2021-08-22T18:02:35+00:00","article:modified_time":"2022-02-05T23:25:13+00:00","twitter:card":"summary_large_image","twitter:title":"Lasa\u00f1a vegetariana con ricota - Verde Oveja","twitter:description":"Deliciosas hamburguesas de cordero rellenas de tu queso de oveja favorito. \u00a1mmm!"},"aioseo_meta_data":{"post_id":"7677","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_image_url":null,"og_image_width":null,"og_image_height":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_image_url":null,"twitter_title":null,"twitter_description":null,"schema_type":"default","schema_type_options":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"created":"2026-05-24 23:45:40","updated":"2026-05-24 23:45:40"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/laverdeoveja.com\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/laverdeoveja.com\/es\/category\/recetas\/\" title=\"Recetas\">Recetas<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/laverdeoveja.com\/es\/category\/recetas\/recetas-de-queso\/\" title=\"recetas de queso\">recetas de queso<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLasa\u00f1a vegetariana con ricota\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/laverdeoveja.com\/es\/"},{"label":"Recetas","link":"https:\/\/laverdeoveja.com\/es\/category\/recetas\/"},{"label":"recetas de queso","link":"https:\/\/laverdeoveja.com\/es\/category\/recetas\/recetas-de-queso\/"},{"label":"Lasa\u00f1a vegetariana con ricota","link":"https:\/\/laverdeoveja.com\/es\/lasana-vegetariana-con-ricota\/"}],"jetpack_featured_media_url":"https:\/\/laverdeoveja.com\/wp-content\/uploads\/2021\/08\/Vegetarian-Lasagna-011.jpg","jetpack_sharing_enabled":true,"builder_content":"<p>Lasa\u00f1a vegetariana con ricota<\/p>\n<p>Receta proporcionada por: Sonja Overhiser en <a href=\"https:\/\/www.acouplecooks.com\/vegetarian-lasagna-with-ricotta\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.acouplecooks.com\/vegetarian-lasagna-with-ricotta\/<\/a><\/p>\n<p><strong>Porciones<\/strong> : 9 | <strong>Tiempo de preparaci\u00f3n:<\/strong> 45 minutos | <strong>Tiempo de cocci\u00f3n<\/strong> : 50 minutos<\/p>\n<p><strong>\u00a1Esta receta de lasa\u00f1a vegetariana es un placer total! El relleno f\u00e1cil de espinacas y queso ricotta es cl\u00e1sico y cremoso.<\/strong>.<\/p>\n<h3><strong>INGREDIENTES<\/strong><\/h3>\n<p><strong>Para la salsa de tomate (o sustituya 4 tazas de su salsa marinara favorita)<\/strong><\/p>\n<ul> <li>4 dientes de ajo grandes<\/li> <li>2 cucharadas de mantequilla sin sal<\/li> <li>1 lata de 28 onzas de tomates triturados, asados al fuego si es posible<\/li> <li>1 lata de salsa de tomate de 15 onzas, asada al fuego si es posible<\/li> <li>1 cucharadita de albahaca seca<\/li> <li>1 cucharadita de estrag\u00f3n seco (u or\u00e9gano)<\/li> <li>\u00be cucharadita <a href=\"https:\/\/www.acouplecooks.com\/what-is-kosher-salt\/\" target=\"_blank\" rel=\"noopener\" data-tasty-links-no-disclosure=\"\">de sal kosher<\/a><\/li> <li>1 cucharada de maicena (o almid\u00f3n de arrurruz)<\/li> <\/ul>\n<p><strong>para la lasa\u00f1a<\/strong><\/p>\n<ul> <li>10 a 12 fideos de lasa\u00f1a ( 8 onzas , sin gluten seg\u00fan sea necesario)*<\/li> <li>5 onzas de espinacas tiernas** (u 8 tazas de espinacas picadas)<\/li> <li>2 cucharadas de tomillo fresco picado<\/li> <li>Zest of 1\/2 lemon (about 2 teaspoons)<\/li> <li>\u00bc de cucharadita de nuez moscada molida<\/li> <li>16 onzas ( 2 tazas ) de queso ricotta<\/li> <li>1 taza de queso parmesano rallado, dividido<\/li> <li>3 tazas ( 12 onzas ) de queso mozzarella rallado, cantidad dividida<\/li> <li>1 cucharadita de <a href=\"https:\/\/www.acouplecooks.com\/what-is-kosher-salt\/\" target=\"_blank\" rel=\"noopener\" data-tasty-links-no-disclosure=\"\">sal kosher<\/a><\/li> <li>Pimienta negra molida fresca<\/li> <\/ul>\n<h3><strong>NOTAS<\/strong><\/h3>\n<p>*Si usa fideos de lasa\u00f1a frescos, no es necesario hervirlos. <\/p> <p>**Tambi\u00e9n puede sustituir \u00be taza de espinacas congeladas. Descong\u00e9lalo y exprime el exceso de l\u00edquido: puedes saltarte el paso de cocci\u00f3n. <\/p>\n<h3><strong>DIRECCIONES<\/strong><\/h3>\n<ol> <li id=\"instruction-step-1\"><strong>Precalentar:<\/strong> Precaliente el horno a 375 grados Fahrenheit.<\/li> <li id=\"instruction-step-2\"><strong>Hervir los fideos*:<\/strong> Poner a hervir una olla grande con agua bien salada. Hervir los fideos hasta que est\u00e9n justo antes de que est\u00e9n al dente, de acuerdo con las instrucciones del paquete, revolviendo con frecuencia. Escurra los fideos, luego roc\u00ede una bandeja para hornear con un poco de aceite de oliva. Coloque los fideos planos sobre la hoja, luego volt\u00e9elos para que se cubran con aceite de oliva para evitar que se peguen.<\/li> <li id=\"instruction-step-3\"><strong>Preparar la salsa de tomate (o saltear con marinara comprada):<\/strong> <a href=\"https:\/\/www.acouplecooks.com\/how-to-mince-garlic\/\" target=\"_blank\" rel=\"noopener\" data-tasty-links-no-disclosure=\"\">Picar el ajo<\/a> . Derrita la mantequilla en una cacerola a fuego medio. Agregue el ajo y saltee, revolviendo con frecuencia. Una vez que el ajo est\u00e9 fragante despu\u00e9s de aproximadamente 1 o 2 minutos, baje el fuego y agregue con cuidado los tomates, la salsa de tomate, la albahaca, el estrag\u00f3n u or\u00e9gano, <a href=\"https:\/\/www.acouplecooks.com\/what-is-kosher-salt\/\" target=\"_blank\" rel=\"noopener\" data-tasty-links-no-disclosure=\"\">la sal kosher<\/a> y varios granos de pimienta negra molida. Retire \u00bc de taza de la salsa y revu\u00e9lvala con la maicena, luego agr\u00e9guela nuevamente a la sart\u00e9n (esto ayuda a espesar la salsa). Cocine a fuego lento mientras hace el resto de la receta, al menos 15 minutos. Cuando est\u00e9 listo para usar, retire la sart\u00e9n del fuego.<\/li> <li id=\"instruction-step-4\"><strong>Marchitar las espinacas:<\/strong> En una sart\u00e9n grande, amontone las verduras y \u00bc de taza de agua en la sart\u00e9n y cocine, revolviendo con frecuencia, hasta que est\u00e9n completamente marchitas y reducidas, aproximadamente 3 minutos (las verduras se reducen significativamente al cocinar; si es necesario, saltee en lotes). Espolvorear con 2 pizcas de <a href=\"https:\/\/www.acouplecooks.com\/what-is-kosher-salt\/\" target=\"_blank\" rel=\"noopener\" data-tasty-links-no-disclosure=\"\">sal kosher<\/a> y revuelva, luego retire del fuego y deje que se enfr\u00ede un poco. Una vez enfriado, use sus manos para exprimir todo el exceso de l\u00edquido y des\u00e9chelo. Picar las espinacas en trozos grandes.<\/li> <li id=\"instruction-step-5\"><strong>Preparar el relleno de queso:<\/strong> Despalillar el tomillo y picar las hojas. Agregue 1 \u00bd cucharadas de tomillo a un taz\u00f3n mediano y reserve aproximadamente \u00bd cucharada para cubrir la lasa\u00f1a. En el taz\u00f3n, agregue la ralladura de lim\u00f3n, la nuez moscada, el queso ricotta, \u00be de taza de queso parmesano, 2 tazas de queso mozzarella rallado, <a href=\"https:\/\/www.acouplecooks.com\/what-is-kosher-salt\/\" target=\"_blank\" rel=\"noopener\" data-tasty-links-no-disclosure=\"\">sal kosher<\/a> y varios granos de pimienta negra. Revuelve para combinar.<\/li> <li id=\"instruction-step-6\"><strong>Coloque la lasa\u00f1a en capas:<\/strong> en una fuente para hornear de 9 \"x 13\", extienda \u00bd taza de salsa de tomate en el fondo de la fuente. Luego cubra con 1 capa de fideos, la mitad de la mezcla de queso (en porciones y luego exti\u00e9ndala), la mitad de las verduras y aproximadamente 1 taza de salsa de tomate. Repita nuevamente: 1 capa de fideos (es posible que deba cortar un fideo por la mitad para el costado, dependiendo de su sart\u00e9n), la mezcla de queso restante, las verduras restantes y 1 taza de salsa de tomate. Finalmente, cubra con fideos (nuevamente, es posible que deba cortar un fideo por la mitad para la capa superior), luego las 1 \u00bd tazas restantes de la salsa de tomate. Espolvorea toda la parte superior con la 1 taza restante de queso mozzarella, \u00bc de taza de queso parmesano y \u00bd cucharada de tomillo.<\/li> <li id=\"instruction-step-7\"><strong>Hornea la lasa\u00f1a:<\/strong> Cubra la fuente con papel aluminio y hornee por 40 minutos. Retire con cuidado el papel aluminio y hornee otros 10 minutos, hasta que burbujee y se dore. Deje reposar durante 15 minutos antes de servir (esto permite que la lasa\u00f1a se asiente). Las sobras se pueden refrigerar durante 2 a 3 d\u00edas y recalentar en un horno a 375 \u00b0F.<\/li> <\/ol>\n<a href=\"https:\/\/laverdeoveja.com\/shop\/ricotta\/\" target=\"_blank\" rel=\"noopener\"> <em><svg xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" aria-hidden=\"true\"><use href=\"#tf-ti-shopping-cart\" xlink:href=\"#tf-ti-shopping-cart\"><\/use><\/svg><\/em> Comprar ricota <\/a>","_links":{"self":[{"href":"https:\/\/laverdeoveja.com\/es\/wp-json\/wp\/v2\/posts\/7677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laverdeoveja.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laverdeoveja.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laverdeoveja.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/laverdeoveja.com\/es\/wp-json\/wp\/v2\/comments?post=7677"}],"version-history":[{"count":2,"href":"https:\/\/laverdeoveja.com\/es\/wp-json\/wp\/v2\/posts\/7677\/revisions"}],"predecessor-version":[{"id":8020,"href":"https:\/\/laverdeoveja.com\/es\/wp-json\/wp\/v2\/posts\/7677\/revisions\/8020"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laverdeoveja.com\/es\/wp-json\/wp\/v2\/media\/7540"}],"wp:attachment":[{"href":"https:\/\/laverdeoveja.com\/es\/wp-json\/wp\/v2\/media?parent=7677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laverdeoveja.com\/es\/wp-json\/wp\/v2\/categories?post=7677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laverdeoveja.com\/es\/wp-json\/wp\/v2\/tags?post=7677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}