{"id":7727,"date":"2021-02-04T14:20:27","date_gmt":"2021-02-04T19:20:27","guid":{"rendered":"https:\/\/laverdeoveja.com\/shop\/leche-jersey-de-bambi\/"},"modified":"2022-09-20T12:27:28","modified_gmt":"2022-09-20T17:27:28","slug":"jersey-milk-by-bambi","status":"publish","type":"product","link":"https:\/\/laverdeoveja.com\/es\/producto\/jersey-milk-by-bambi\/","title":{"rendered":"Leche Jersey de \u00abBambi\u00bb"},"content":{"rendered":"<p><span style=\"color: #3d30303; font-weight: 300;font-family: merriweather sans;\">Leche fresca, natural y pasteurizada de vaca Jersey de \u201cBambi\u201d. Esta leche tiene una vida \u00fatil de dos semanas en el refrigerador. No est\u00e1 homogeneizado, por lo que, naturalmente, la capa de crema se separar\u00e1 en la parte superior del recipiente. El rico color amarillo de la crema proviene del betacaroteno que Bambi concentra de su dieta rica en pastos y minerales. <\/span><\/p>\n<p><span style=\"color: #3d30303; font-weight: 300;font-family: merriweather sans;\">Tambi\u00e9n presentamos esta leche en una versi\u00f3n baja en grasa (desnatada hasta aproximadamente un 1,5-2% de grasa). \u00a1Aseg\u00farese de elegir el producto exacto que desea tener!<\/span><\/p>\n<ul>\n<li><span style=\"color: #3d30303; font-weight: 300;font-family: merriweather sans;\">1\/2 Gal\u00f3n de Leche Entera: $3.00<\/span><\/li>\n<li><span style=\"color: #3d30303; font-weight: 300;font-family: merriweather sans;\">1 Gal\u00f3n de Leche Entera: $6.00<\/span><\/li>\n<li><span style=\"color: #3d30303; font-weight: 300;font-family: merriweather sans;\">1\/2 gal\u00f3n bajo en grasa (1.5-2%): $3.25<\/span><\/li>\n<li><span style=\"color: #3d30303; font-weight: 300;font-family: merriweather sans;\">1 gal\u00f3n bajo en grasa (1.5-2%): $6.50<\/span><\/li>\n<\/ul>\n<!--themify_builder_content-->\n<div id=\"themify_builder_content-7727\" data-postid=\"7727\" class=\"themify_builder_content themify_builder_content-7727 themify_builder tf_clear\">\n    <\/div>\n<!--\/themify_builder_content-->\n","protected":false},"excerpt":{"rendered":"<p><span style=\"color: #3d30303; font-weight: 300;font-family: merriweather sans;\">Leche fresca, natural y pasteurizada de vaca Jersey de \u201cBambi\u201d. Esta leche tiene una vida \u00fatil de dos semanas en el refrigerador. No est\u00e1 homogeneizado, por lo que, naturalmente, la capa de crema se separar\u00e1 en la parte superior del recipiente. El rico color amarillo de la crema proviene del betacaroteno que Bambi concentra de su dieta rica en pastos y minerales. Tambi\u00e9n presentamos esta leche en una versi\u00f3n baja en grasa (desnatada hasta aproximadamente un 1,5-2% de grasa).<\/span><\/p>\n<ul>\n<li><span style=\"color: #3d30303; font-weight: 300;font-family: merriweather sans;\">1\/2 Gal\u00f3n de Leche Entera: $3.00<\/span><\/li>\n<li><span style=\"color: #3d30303; font-weight: 300;font-family: merriweather sans;\">1 Gal\u00f3n de Leche Entera: $6.00<\/span><\/li>\n<li><span style=\"color: #3d30303; font-weight: 300;font-family: merriweather sans;\">1\/2 gal\u00f3n bajo en grasa (1.5-2%): $3.25<\/span><\/li>\n<li><span style=\"color: #3d30303; font-weight: 300;font-family: merriweather sans;\">1 gal\u00f3n bajo en grasa (1.5-2%): $6.50<\/span><\/li>\n<\/ul>\n","protected":false},"featured_media":7534,"comment_status":"open","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_brand":[],"product_cat":[275],"product_tag":[],"class_list":["post-7727","product","type-product","status-publish","has-post-thumbnail","product_cat-queso","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author","","first","instock","featured","purchasable","product-type-variable"],"group_of_quantity":0,"min_quantity":0,"max_quantity":"","exclude_order_quantity_value_rules":"no","exclude_category_quantity_rules":"no","combine_variations":"no","aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Leche fresca, natural y pasteurizada de vaca Jersey de \u201cBambi\u201d. Esta leche tiene una vida \u00fatil de dos semanas en el refrigerador. No est\u00e1 homogeneizado, por lo que, naturalmente, la capa de crema se separar\u00e1 en la parte superior del recipiente. El rico color amarillo de la crema proviene del betacaroteno que Bambi concentra de su dieta rica en pastos y minerales. Tambi\u00e9n presentamos esta leche en una versi\u00f3n baja en grasa (desnatada hasta aproximadamente un 1,5-2% de grasa). 1\/2 Gal\u00f3n de Leche Entera: $3.00 1 Gal\u00f3n de Leche Entera: $6.00 1\/2 gal\u00f3n bajo en grasa (1.5-2%): $3.25 1 gal\u00f3n bajo en grasa (1.5-2%): $6.50\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/laverdeoveja.com\/es\/producto\/jersey-milk-by-bambi\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Verde Oveja -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Leche Jersey de \u00abBambi\u00bb - Verde Oveja\" \/>\n\t\t<meta property=\"og:description\" content=\"Leche fresca, natural y pasteurizada de vaca Jersey de \u201cBambi\u201d. Esta leche tiene una vida \u00fatil de dos semanas en el refrigerador. No est\u00e1 homogeneizado, por lo que, naturalmente, la capa de crema se separar\u00e1 en la parte superior del recipiente. El rico color amarillo de la crema proviene del betacaroteno que Bambi concentra de su dieta rica en pastos y minerales. Tambi\u00e9n presentamos esta leche en una versi\u00f3n baja en grasa (desnatada hasta aproximadamente un 1,5-2% de grasa). 1\/2 Gal\u00f3n de Leche Entera: $3.00 1 Gal\u00f3n de Leche Entera: $6.00 1\/2 gal\u00f3n bajo en grasa (1.5-2%): $3.25 1 gal\u00f3n bajo en grasa (1.5-2%): $6.50\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/laverdeoveja.com\/es\/producto\/jersey-milk-by-bambi\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-02-04T19:20:27+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-09-20T17:27:28+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Leche Jersey de \u00abBambi\u00bb - Verde Oveja\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Leche fresca, natural y pasteurizada de vaca Jersey de \u201cBambi\u201d. Esta leche tiene una vida \u00fatil de dos semanas en el refrigerador. No est\u00e1 homogeneizado, por lo que, naturalmente, la capa de crema se separar\u00e1 en la parte superior del recipiente. El rico color amarillo de la crema proviene del betacaroteno que Bambi concentra de su dieta rica en pastos y minerales. Tambi\u00e9n presentamos esta leche en una versi\u00f3n baja en grasa (desnatada hasta aproximadamente un 1,5-2% de grasa). 1\/2 Gal\u00f3n de Leche Entera: $3.00 1 Gal\u00f3n de Leche Entera: $6.00 1\/2 gal\u00f3n bajo en grasa (1.5-2%): $3.25 1 gal\u00f3n bajo en grasa (1.5-2%): $6.50\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/producto\\\/jersey-milk-by-bambi\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/categoria-producto\\\/queso\\\/#listItem\",\"name\":\"Queso\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/categoria-producto\\\/queso\\\/#listItem\",\"position\":2,\"name\":\"Queso\",\"item\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/categoria-producto\\\/queso\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/producto\\\/jersey-milk-by-bambi\\\/#listItem\",\"name\":\"Leche Jersey de \\u00abBambi\\u00bb\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/producto\\\/jersey-milk-by-bambi\\\/#listItem\",\"position\":3,\"name\":\"Leche Jersey de \\u00abBambi\\u00bb\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/categoria-producto\\\/queso\\\/#listItem\",\"name\":\"Queso\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/producto\\\/jersey-milk-by-bambi\\\/#itempage\",\"url\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/producto\\\/jersey-milk-by-bambi\\\/\",\"name\":\"Leche Jersey de \\u00abBambi\\u00bb - Verde Oveja\",\"description\":\"Leche fresca, natural y pasteurizada de vaca Jersey de \\u201cBambi\\u201d. Esta leche tiene una vida \\u00fatil de dos semanas en el refrigerador. No est\\u00e1 homogeneizado, por lo que, naturalmente, la capa de crema se separar\\u00e1 en la parte superior del recipiente. El rico color amarillo de la crema proviene del betacaroteno que Bambi concentra de su dieta rica en pastos y minerales. Tambi\\u00e9n presentamos esta leche en una versi\\u00f3n baja en grasa (desnatada hasta aproximadamente un 1,5-2% de grasa). 1\\\/2 Gal\\u00f3n de Leche Entera: $3.00 1 Gal\\u00f3n de Leche Entera: $6.00 1\\\/2 gal\\u00f3n bajo en grasa (1.5-2%): $3.25 1 gal\\u00f3n bajo en grasa (1.5-2%): $6.50\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/producto\\\/jersey-milk-by-bambi\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/laverdeoveja.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/jumpstory-download20210720-194046.jpg\",\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/producto\\\/jersey-milk-by-bambi\\\/#mainImage\",\"width\":1562,\"height\":1920},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/producto\\\/jersey-milk-by-bambi\\\/#mainImage\"},\"datePublished\":\"2021-02-04T14:20:27-05:00\",\"dateModified\":\"2022-09-20T12:27:28-05:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/#organization\",\"name\":\"Verde Oveja\",\"url\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/\",\"name\":\"Verde Oveja\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/laverdeoveja.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Leche Jersey de \u00abBambi\u00bb - Verde Oveja","description":"Leche fresca, natural y pasteurizada de vaca Jersey de \u201cBambi\u201d. Esta leche tiene una vida \u00fatil de dos semanas en el refrigerador. No est\u00e1 homogeneizado, por lo que, naturalmente, la capa de crema se separar\u00e1 en la parte superior del recipiente. El rico color amarillo de la crema proviene del betacaroteno que Bambi concentra de su dieta rica en pastos y minerales. Tambi\u00e9n presentamos esta leche en una versi\u00f3n baja en grasa (desnatada hasta aproximadamente un 1,5-2% de grasa). 1\/2 Gal\u00f3n de Leche Entera: $3.00 1 Gal\u00f3n de Leche Entera: $6.00 1\/2 gal\u00f3n bajo en grasa (1.5-2%): $3.25 1 gal\u00f3n bajo en grasa (1.5-2%): $6.50","canonical_url":"https:\/\/laverdeoveja.com\/es\/producto\/jersey-milk-by-bambi\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/laverdeoveja.com\/es\/producto\/jersey-milk-by-bambi\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/laverdeoveja.com\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/laverdeoveja.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/laverdeoveja.com\/es\/categoria-producto\/queso\/#listItem","name":"Queso"}},{"@type":"ListItem","@id":"https:\/\/laverdeoveja.com\/es\/categoria-producto\/queso\/#listItem","position":2,"name":"Queso","item":"https:\/\/laverdeoveja.com\/es\/categoria-producto\/queso\/","nextItem":{"@type":"ListItem","@id":"https:\/\/laverdeoveja.com\/es\/producto\/jersey-milk-by-bambi\/#listItem","name":"Leche Jersey de \u00abBambi\u00bb"},"previousItem":{"@type":"ListItem","@id":"https:\/\/laverdeoveja.com\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/laverdeoveja.com\/es\/producto\/jersey-milk-by-bambi\/#listItem","position":3,"name":"Leche Jersey de \u00abBambi\u00bb","previousItem":{"@type":"ListItem","@id":"https:\/\/laverdeoveja.com\/es\/categoria-producto\/queso\/#listItem","name":"Queso"}}]},{"@type":"ItemPage","@id":"https:\/\/laverdeoveja.com\/es\/producto\/jersey-milk-by-bambi\/#itempage","url":"https:\/\/laverdeoveja.com\/es\/producto\/jersey-milk-by-bambi\/","name":"Leche Jersey de \u00abBambi\u00bb - Verde Oveja","description":"Leche fresca, natural y pasteurizada de vaca Jersey de \u201cBambi\u201d. Esta leche tiene una vida \u00fatil de dos semanas en el refrigerador. No est\u00e1 homogeneizado, por lo que, naturalmente, la capa de crema se separar\u00e1 en la parte superior del recipiente. El rico color amarillo de la crema proviene del betacaroteno que Bambi concentra de su dieta rica en pastos y minerales. Tambi\u00e9n presentamos esta leche en una versi\u00f3n baja en grasa (desnatada hasta aproximadamente un 1,5-2% de grasa). 1\/2 Gal\u00f3n de Leche Entera: $3.00 1 Gal\u00f3n de Leche Entera: $6.00 1\/2 gal\u00f3n bajo en grasa (1.5-2%): $3.25 1 gal\u00f3n bajo en grasa (1.5-2%): $6.50","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/laverdeoveja.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/laverdeoveja.com\/es\/producto\/jersey-milk-by-bambi\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/laverdeoveja.com\/wp-content\/uploads\/2021\/07\/jumpstory-download20210720-194046.jpg","@id":"https:\/\/laverdeoveja.com\/es\/producto\/jersey-milk-by-bambi\/#mainImage","width":1562,"height":1920},"primaryImageOfPage":{"@id":"https:\/\/laverdeoveja.com\/es\/producto\/jersey-milk-by-bambi\/#mainImage"},"datePublished":"2021-02-04T14:20:27-05:00","dateModified":"2022-09-20T12:27:28-05:00"},{"@type":"Organization","@id":"https:\/\/laverdeoveja.com\/es\/#organization","name":"Verde Oveja","url":"https:\/\/laverdeoveja.com\/es\/"},{"@type":"WebSite","@id":"https:\/\/laverdeoveja.com\/es\/#website","url":"https:\/\/laverdeoveja.com\/es\/","name":"Verde Oveja","inLanguage":"es-ES","publisher":{"@id":"https:\/\/laverdeoveja.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Verde Oveja -","og:type":"article","og:title":"Leche Jersey de \u00abBambi\u00bb - Verde Oveja","og:description":"Leche fresca, natural y pasteurizada de vaca Jersey de \u201cBambi\u201d. Esta leche tiene una vida \u00fatil de dos semanas en el refrigerador. No est\u00e1 homogeneizado, por lo que, naturalmente, la capa de crema se separar\u00e1 en la parte superior del recipiente. El rico color amarillo de la crema proviene del betacaroteno que Bambi concentra de su dieta rica en pastos y minerales. Tambi\u00e9n presentamos esta leche en una versi\u00f3n baja en grasa (desnatada hasta aproximadamente un 1,5-2% de grasa). 1\/2 Gal\u00f3n de Leche Entera: $3.00 1 Gal\u00f3n de Leche Entera: $6.00 1\/2 gal\u00f3n bajo en grasa (1.5-2%): $3.25 1 gal\u00f3n bajo en grasa (1.5-2%): $6.50","og:url":"https:\/\/laverdeoveja.com\/es\/producto\/jersey-milk-by-bambi\/","article:published_time":"2021-02-04T19:20:27+00:00","article:modified_time":"2022-09-20T17:27:28+00:00","twitter:card":"summary_large_image","twitter:title":"Leche Jersey de \u00abBambi\u00bb - Verde Oveja","twitter:description":"Leche fresca, natural y pasteurizada de vaca Jersey de \u201cBambi\u201d. Esta leche tiene una vida \u00fatil de dos semanas en el refrigerador. No est\u00e1 homogeneizado, por lo que, naturalmente, la capa de crema se separar\u00e1 en la parte superior del recipiente. El rico color amarillo de la crema proviene del betacaroteno que Bambi concentra de su dieta rica en pastos y minerales. Tambi\u00e9n presentamos esta leche en una versi\u00f3n baja en grasa (desnatada hasta aproximadamente un 1,5-2% de grasa). 1\/2 Gal\u00f3n de Leche Entera: $3.00 1 Gal\u00f3n de Leche Entera: $6.00 1\/2 gal\u00f3n bajo en grasa (1.5-2%): $3.25 1 gal\u00f3n bajo en grasa (1.5-2%): $6.50"},"aioseo_meta_data":{"post_id":"7727","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_image_url":null,"og_image_width":null,"og_image_height":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_image_url":null,"twitter_title":null,"twitter_description":null,"schema_type":"default","schema_type_options":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"created":"2026-05-24 23:54:38","updated":"2026-05-24 23:54:38"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/laverdeoveja.com\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/laverdeoveja.com\/es\/categoria-producto\/queso\/\" title=\"Queso\">Queso<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLeche Jersey de \u00abBambi\u00bb\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/laverdeoveja.com\/es\/"},{"label":"Queso","link":"https:\/\/laverdeoveja.com\/es\/categoria-producto\/queso\/"},{"label":"Leche Jersey de \u00abBambi\u00bb","link":"https:\/\/laverdeoveja.com\/es\/producto\/jersey-milk-by-bambi\/"}],"jetpack_sharing_enabled":true,"builder_content":"","_links":{"self":[{"href":"https:\/\/laverdeoveja.com\/es\/wp-json\/wp\/v2\/product\/7727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laverdeoveja.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/laverdeoveja.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/laverdeoveja.com\/es\/wp-json\/wp\/v2\/comments?post=7727"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laverdeoveja.com\/es\/wp-json\/wp\/v2\/media\/7534"}],"wp:attachment":[{"href":"https:\/\/laverdeoveja.com\/es\/wp-json\/wp\/v2\/media?parent=7727"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/laverdeoveja.com\/es\/wp-json\/wp\/v2\/product_brand?post=7727"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/laverdeoveja.com\/es\/wp-json\/wp\/v2\/product_cat?post=7727"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/laverdeoveja.com\/es\/wp-json\/wp\/v2\/product_tag?post=7727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}