{"id":275,"count":15,"description":"En La Verde Oveja, realmente amamos lo que hacemos y eso se nota en la calidad de nuestros productos de la granja a la mesa. Nuestro queso se elabora fresco y envejecido en nuestra granja sostenible y nuestras ovejas est\u00e1n sumamente cuidadas. Este cuidado y calidad nos permite elaborar los mejores quesos artesanales disponibles en el Ecuador.","link":"https:\/\/laverdeoveja.com\/es\/categoria-producto\/queso\/","name":"Queso","slug":"queso","taxonomy":"product_cat","parent":0,"meta":{"group_of_quantity":""},"menu_order":0,"_links":{"self":[{"href":"https:\/\/laverdeoveja.com\/es\/wp-json\/wp\/v2\/product_cat\/275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laverdeoveja.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/laverdeoveja.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/laverdeoveja.com\/es\/wp-json\/wp\/v2\/product?product_cat=275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}